{"id":11418,"date":"2024-10-30T11:28:02","date_gmt":"2024-10-30T10:28:02","guid":{"rendered":"https:\/\/ifeelonline.com\/fr\/?p=11418"},"modified":"2024-11-06T11:10:38","modified_gmt":"2024-11-06T10:10:38","slug":"5-strategies-de-resilience-pour-les-dirigeants","status":"publish","type":"post","link":"https:\/\/ifeelonline.com\/fr\/5-strategies-de-resilience-pour-les-dirigeants\/","title":{"rendered":"D\u00e9couvrez 5 strat\u00e9gies de r\u00e9silience pour les dirigeants"},"content":{"rendered":"\n<p><strong>Pourquoi les strat\u00e9gies de r\u00e9silience pour les dirigeants sont-elles n\u00e9cessaires, me direz-vous ?<\/strong> La v\u00e9rit\u00e9 est que lorsque nous pensons aux responsabilit\u00e9s des managers et des leaders, elles ne se limitent pas \u00e0 la poursuite d&rsquo;objectifs ambitieux, mais aussi \u00e0 \u00eatre ce <strong>guide capable de conduire leurs \u00e9quipes \u00e0 travers une mer d&rsquo;<a href=\"https:\/\/ifeelonline.com\/fr\/gestion-de-crise-en-entreprise\/\">incertitudes<\/a> et de d\u00e9fis.<\/strong> Tout cela doit \u00eatre r\u00e9alis\u00e9 en pr\u00e9servant l&rsquo;\u00e9quilibre de leur propre sant\u00e9 mentale. Ce qui, bien s\u00fbr, n&rsquo;est pas une mince affaire.<\/p>\n\n\n\n<p>Les managers, les dirigeants et les cadres sont aussi des \u00eatres humains ; ils peuvent donc \u00eatre affect\u00e9s par<strong> la pression constante qui caract\u00e9rise leur travail<\/strong>. Et c&rsquo;est normal. Cependant, le fait de devoir donner le meilleur d&rsquo;eux-m\u00eames, de prendre des d\u00e9cisions complexes et d&rsquo;inspirer constamment leurs \u00e9quipes peut exercer <strong>une pression consid\u00e9rable sur leur bien-\u00eatre mental<\/strong>, qui, s&rsquo;il n&rsquo;est pas g\u00e9r\u00e9 correctement, peut conduire \u00e0 une mauvaise sant\u00e9 mentale ou \u00e0 l&rsquo;\u00e9puisement professionnel.<\/p>\n\n\n\n<p>C&rsquo;est pourquoi la sant\u00e9 mentale des dirigeants est consid\u00e9r\u00e9e comme un facteur essentiel qui influe non seulement sur leurs performances individuelles, mais aussi <strong>sur la r\u00e9ussite et la coh\u00e9sion de l&rsquo;ensemble de l&rsquo;\u00e9quipe.<\/strong> Un dirigeant dot\u00e9 d&rsquo;une bonne sant\u00e9 mentale est capable de g\u00e9rer efficacement le stress, de rester lucide dans<strong> <a href=\"https:\/\/ifeelonline.com\/fr\/boite-a-outils-rh\/gestion-de-crise-pour-les-managers\/?partner=ifeel_internLinkPost\">les situations de crise<\/a><\/strong> et d&rsquo;<strong>apporter le soutien n\u00e9cessaire \u00e0 ses \u00e9quipes.<\/strong><\/p>\n\n\n\n<p>Il est donc essentiel de d\u00e9velopper des strat\u00e9gies de r\u00e9silience pour les dirigeants, non seulement pour leur propre durabilit\u00e9, mais aussi pour la <strong>sant\u00e9 de l&rsquo;organisation dans son ensemble.<\/strong><\/p>\n\n\n\n<p>Si vous souhaitez en savoir plus \u00e0 ce sujet, nous vous invitons \u00e0 t\u00e9l\u00e9charger notre <strong><a href=\"https:\/\/ifeelonline.com\/fr\/boite-a-outils-rh\/bien-etre-mental-dans-les-postes-de-direction\/?partner=ifeel_internLinkPost\">livre blanc<\/a> sur la mani\u00e8re de prendre soin de la sant\u00e9 mentale des dirigeants, qui <\/strong>fournira \u00e0 votre \u00e9quipe dirigeante des outils essentiels \u00e0 son bien-\u00eatre. Donnez la priorit\u00e9 \u00e0 la sant\u00e9 mentale dans votre entreprise et fournissez-leur des strat\u00e9gies de r\u00e9silience pour les dirigeants.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;importance de la prise en charge des dirigeants<\/h2>\n\n\n\n<p>Le bien-\u00eatre mental des dirigeants est un sujet qui, bien que crucial, est souvent n\u00e9glig\u00e9. Selon un <a href=\"https:\/\/www.businessgrouphealth.org\/en\/newsroom\/news%20and%20press%20releases\/press%20releases\/2024%20lehcss\" target=\"_blank\" rel=\"noopener\">rapport du Business Group on Health,<\/a> <strong>77 % des grands employeurs ont signal\u00e9 une augmentation des probl\u00e8mes de sant\u00e9 mentale chez leurs employ\u00e9s d&rsquo;ici \u00e0 2023<\/strong>. Un autre <a href=\"https:\/\/hbr.org\/2023\/05\/more-than-50-of-managers-feel-burned-out\" target=\"_blank\" rel=\"noopener\">rapport<\/a> indique que <strong>plus de 50 % des cadres <\/strong>ont d\u00e9clar\u00e9 avoir souffert d&rsquo;<a href=\"https:\/\/ifeelonline.com\/fr\/epuisement-professionnel\/\">\u00e9puisement professionnel<\/a> et de <strong><em>burnout<\/em><\/strong> \u00e0 un moment ou \u00e0 un autre, un chiffre l\u00e9g\u00e8rement sup\u00e9rieur \u00e0 celui de l&#8217;employ\u00e9 moyen.<\/p>\n\n\n\n<p>Ces statistiques soulignent la n\u00e9cessit\u00e9 de<strong> doter les cadres et les dirigeants de strat\u00e9gies de r\u00e9silience pour les leaders<\/strong>, ainsi que d&rsquo;outils efficaces de gestion du stress, afin de permettre le maintien de la sant\u00e9 mentale des cadres sup\u00e9rieurs.<\/p>\n\n\n\n<p>Dans ce contexte, la <strong>r\u00e9silience est le bouclier qui<\/strong> permet aux personnes occupant des postes \u00e0 responsabilit\u00e9 non seulement de r\u00e9sister \u00e0 l&rsquo;adversit\u00e9<strong>, mais aussi de prosp\u00e9rer et de diriger avec confiance et clart\u00e9.<\/strong> Dans un environnement o\u00f9 le changement est la seule constante, ces strat\u00e9gies sont indispensables pour <strong>transformer la pression en opportunit\u00e9s et les d\u00e9fis en apprentissage.<\/strong><\/p>\n\n\n\n<p>Sur ce sujet, les leaders d&rsquo;ifeel ajoutent :<\/p>\n\n\n\n<p><strong>Gabriele Murrone, cofondateur et directeur g\u00e9n\u00e9ral d&rsquo;ifeel,<\/strong> souligne :<\/p>\n\n\n\n<p><em>\u00ab\u00a0Les attentes \u00e0 l&rsquo;\u00e9gard des dirigeants sont toujours tr\u00e8s \u00e9lev\u00e9es.<\/em> <em>C&rsquo;est pourquoi je pense qu&rsquo;il est crucial de concentrer notre attention sur les objectifs qui auront le plus d&rsquo;impact et d&rsquo;apprendre \u00e0 dire non lorsque c&rsquo;est n\u00e9cessaire, afin de prot\u00e9ger notre sant\u00e9 mentale.\u00a0\u00bb<\/em><\/p>\n\n\n\n<p>Cette r\u00e9flexion souligne non seulement l&rsquo;importance de la r\u00e9silience personnelle, mais aussi <strong>la n\u00e9cessit\u00e9 de cr\u00e9er un environnement de travail favorable au bien-\u00eatre mental.<\/strong> La mise en \u0153uvre de strat\u00e9gies de r\u00e9silience pour les dirigeants, de pratiques saines et l&rsquo;\u00e9tablissement de limites claires peuvent aider les dirigeants \u00e0 garder l&rsquo;\u00e9quilibre, optimisant ainsi leur <strong>capacit\u00e9 \u00e0 mener leurs \u00e9quipes vers le succ\u00e8s.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ifeelonline.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/10\/Sante-mentale-managers-1024x683-2.jpg\" alt=\"strat\u00e9gies de r\u00e9silience pour les dirigeants\" class=\"wp-image-11420\" srcset=\"https:\/\/ifeelonline.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/10\/Sante-mentale-managers-1024x683-2.jpg 1024w, https:\/\/ifeelonline.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/10\/Sante-mentale-managers-1024x683-2-300x200.jpg 300w, https:\/\/ifeelonline.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/10\/Sante-mentale-managers-1024x683-2-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Strat\u00e9gies de r\u00e9silience pour les dirigeants<\/h2>\n\n\n\n<p>Le d\u00e9veloppement et le maintien de la r\u00e9silience sont essentiels pour les dirigeants qui <strong>souhaitent relever les d\u00e9fis de l&rsquo;environnement professionnel moderne avec succ\u00e8s et stabilit\u00e9<\/strong>.<\/p>\n\n\n\n<p>L&rsquo;ifeel vous invite \u00e0 t\u00e9l\u00e9charger notre livre blanc sur la mani\u00e8re de<strong> <a href=\"https:\/\/ifeelonline.com\/fr\/boite-a-outils-rh\/bien-etre-mental-dans-les-postes-de-direction\/?partner=ifeel_internLinkPost\">prendre soin de la sant\u00e9 mentale des dirigeants<\/a>.<\/strong> Vous y apprendrez tout sur les strat\u00e9gies de r\u00e9silience pour les dirigeants, afin de fournir \u00e0 votre \u00e9quipe de direction des outils essentiels \u00e0 leur bien-\u00eatre.<\/p>\n\n\n\n<p>Vous trouverez ci-dessous <strong>plusieurs strat\u00e9gies pratiques <\/strong>que les dirigeants peuvent adopter pour renforcer leur r\u00e9silience et pr\u00e9server leur bien-\u00eatre mental, ce qui leur permettra de diriger avec confiance et clart\u00e9, malgr\u00e9 l&rsquo;adversit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conscience de soi et soins personnels<\/h3>\n\n\n\n<p>La premi\u00e8re \u00e9tape du d\u00e9veloppement de la r\u00e9silience est la connaissance de soi. Les dirigeants doivent \u00eatre conscients de leurs propres \u00e9motions, de leurs points forts et des domaines \u00e0 am\u00e9liorer. Cette connaissance de soi leur permet de <strong>mettre en \u0153uvre des pratiques efficaces<\/strong> <strong>de <em><a href=\"https:\/\/ifeelonline.com\/fr\/selfcare-au-travail\/\">selfcare<\/a><\/em><\/strong><em>,<\/em> qui sont le fondement de la r\u00e9silience.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Exercice pratique : \u00e9valuation du bien-\u00eatre<\/strong><\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Tracez un grand cercle sur une feuille de papier repr\u00e9sentant le <strong>temps total dont vous disposez <\/strong>chaque jour.<br><\/li>\n\n\n\n<li>Divisez le cercle en sections repr\u00e9sentant diff\u00e9rents domaines importants (famille, travail, loisirs, repos, soins personnels, etc <strong>.<\/strong><br><\/li>\n\n\n\n<li>R\u00e9fl\u00e9chissez \u00e0 la r\u00e9partition du temps dont vous disposez actuellement et demandez-vous<strong>si vous consacrez suffisamment d&rsquo;attention \u00e0 chaque domaine.<\/strong> Identifiez les domaines dans lesquels vous pourriez consacrer plus de temps pour prendre<strong> soin de votre sant\u00e9 mentale.<\/strong><\/li>\n<\/ol>\n\n\n\n<p>\u00ab <em>Je consacre beaucoup d&rsquo;efforts \u00e0 la connaissance de soi et \u00e0 la pr\u00e9vention.<\/em> <em>Au fil du temps, j&rsquo;ai d\u00e9couvert que certaines activit\u00e9s m&rsquo;aidaient \u00e0 atteindre des \u00e9tats de calme et de connexion avec moi-m\u00eame, comme la peinture, la lecture et le yoga.<\/em> <em>Mais surtout, compter sur mes amis et ma famille est<\/em><strong><em><strong> fondamental pour mon bien-\u00eatre mental\u00a0\u00bb<\/strong><\/em><\/strong><em>.<\/em> &#8211;<strong>Beatriz Juli\u00e1n Almarcegui,<\/strong> responsable des ressources humaines chez <strong>ifeel<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fixer des limites<\/h3>\n\n\n\n<p><strong>Savoir dire \u00ab non \u00bb <\/strong>et fixer des limites claires entre le travail et la vie priv\u00e9e est essentiel et fait partie des strat\u00e9gies de r\u00e9silience des dirigeants.<\/p>\n\n\n\n<p>Les limites ne <strong>prot\u00e8gent pas seulement le temps et l&rsquo;\u00e9nergie du dirigeant<\/strong>, mais servent aussi \u00e0 donner un <strong>exemple sain<\/strong> au reste de l&rsquo;\u00e9quipe. Ce tableau pr\u00e9sente des strat\u00e9gies claires pour fixer des limites et favoriser un \u00e9quilibre sain entre vie professionnelle et vie personnelle.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Strat\u00e9gie<\/strong><\/th><th><strong>Description<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Horaires de travail sp\u00e9cifiques<\/td><td>D\u00e9finissez et respectez les horaires de travail, en \u00e9vitant de r\u00e9pondre aux courriels en dehors de ces horaires.<\/td><\/tr><tr><td>Hi\u00e9rarchiser les t\u00e2ches<\/td><td>Concentrez-vous sur les t\u00e2ches essentielles et d\u00e9l\u00e9guez les t\u00e2ches moins importantes lorsque c&rsquo;est possible.<\/td><\/tr><tr><td>D\u00e9connexion num\u00e9rique<\/td><td>Mettez en place des p\u00e9riodes sans appareils \u00e9lectroniques pour r\u00e9duire le stress et am\u00e9liorer le repos.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Favoriser une culture de soutien<\/h3>\n\n\n\n<p>Une autre strat\u00e9gie de r\u00e9silience pour les dirigeants consiste \u00e0 cr\u00e9er des environnements sains dans lesquels tous les employ\u00e9s, quel que soit leur rang, peuvent parler de leurs \u00e9motions et de leurs besoins sans tabou. Les dirigeants doivent cr\u00e9er un environnement de <a href=\"https:\/\/ifeelonline.com\/fr\/securite-psychologique\/\">s\u00e9curit\u00e9 psychologique<\/a>, o\u00f9 une communication honn\u00eate sur la sant\u00e9 mentale est la bienvenue. Il s&rsquo;agit notamment d&rsquo;<strong>encourager la participation \u00e0 des programmes de bien-\u00eatre et d&rsquo;offrir des ressources de soutien.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">D\u00e9velopper les capacit\u00e9s d&rsquo;adaptation<\/h3>\n\n\n\n<p>Les capacit\u00e9s d&rsquo;adaptation sont essentielles pour g\u00e9rer le stress et les pressions li\u00e9es au leadership. Il s&rsquo;agit notamment de <strong>techniques de gestion du stress, de r\u00e9solution des probl\u00e8mes et de gestion du temps<\/strong>.<\/p>\n\n\n\n<p>Un exemple de ces techniques est la<strong>respiration profonde<\/strong>. Pour les mettre en \u0153uvre, vous devez<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Vous asseoir confortablement, les pieds sur le sol et les mains sur les genoux.<\/li>\n\n\n\n<li>Inspirez profond\u00e9ment par le nez pendant cinq secondes.<\/li>\n\n\n\n<li>Retenez votre souffle pendant trois secondes.<\/li>\n\n\n\n<li>Expirez lentement par la bouche pendant cinq secondes.<\/li>\n\n\n\n<li>R\u00e9p\u00e9tez le processus cinq \u00e0 dix fois.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Demandez l&rsquo;aide d&rsquo;un professionnel<\/h3>\n\n\n\n<p><strong>Demander de l&rsquo;aide est un signe de force et<\/strong> non de faiblesse. Les dirigeants peuvent tirer un grand profit d&rsquo;une <strong>consultation avec des psychologues<\/strong> et des conseillers <strong>experts<\/strong> qui leur permettront de d\u00e9velopper des <strong>strat\u00e9gies de<\/strong> r\u00e9silience <strong>personnalis\u00e9es<\/strong>.<\/p>\n\n\n\n<p>En outre, le <strong>\u00ab <a href=\"https:\/\/ifeelonline.com\/fr\/boite-a-outils-rh\/kit-de-premiers-secours-pour-les-responsables-rh\/?partner=ifeel_internLinkPost\">Kit de premiers secours pour les responsables RH<\/a><\/strong> \u00bb d&rsquo;<strong>ifeel<\/strong> fournit des outils cl\u00e9s pour faire face aux situations critiques sur le lieu de travail.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"708\" height=\"380\" src=\"https:\/\/ifeelonline.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/10\/soutien-psy-2.jpg\" alt=\"sant\u00e9 mentale au travail\" class=\"wp-image-11400\" srcset=\"https:\/\/ifeelonline.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/10\/soutien-psy-2.jpg 708w, https:\/\/ifeelonline.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/10\/soutien-psy-2-300x161.jpg 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Le leader europ\u00e9en des solutions de bien-\u00eatre mental pour les grandes organisations<\/h2>\n\n\n\n<p>Chez <strong>ifeel,<\/strong> nous savons que les strat\u00e9gies de r\u00e9silience pour les dirigeants sont essentielles pour les personnes qui guident les d\u00e9cisions de l&rsquo;entreprise. Les organisations qui investissent dans le bien-\u00eatre et la r\u00e9silience de leurs dirigeants construisent une <strong>base solide pour un succ\u00e8s \u00e0 long terme<\/strong>. Cependant, nous comprenons que le d\u00e9veloppement de la r\u00e9silience est un voyage permanent qui n\u00e9cessite de l&rsquo;engagement et de la pratique.<\/p>\n\n\n\n<p>Notre \u00e9quipe de\u00a0<a href=\"https:\/\/ifeelonline.com\/fr\/notre-departement-de-recherche-clinique\/\">psychologues<\/a>, experts en bien-\u00eatre au travail, a cr\u00e9\u00e9<strong>\u00a0un programme de bien-\u00eatre mental pour les travailleurs\u00a0<\/strong>qui a un impact positif sur\u00a0<strong><a href=\"https:\/\/ifeelonline.com\/fr\/boite-a-outils-rh\/manuel-comment-prevenir-le-burnout-au-travail\/?partner=ifeel_internLinkPost\">la pr\u00e9vention du burnout<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/ifeelonline.com\/fr\/comment-reduire-l-absenteisme\/\">la r\u00e9duction de l\u2019absent\u00e9isme<\/a><\/strong>\u00a0et la lutte contre\u00a0<strong><a href=\"https:\/\/ifeelonline.com\/fr\/outils\/identifier-le-stress-parmi-vos-employes\/?partner=ifeel_internLinkPost\">le stress des collaborateurs<\/a><\/strong>.<\/p>\n\n\n\n<p>Nous travaillons en partenariat avec des entreprises du monde entier pour&nbsp;<strong>inspirer la croissance humaine et guider les organisations<\/strong>&nbsp;dans l\u2019instauration d\u2019une&nbsp;<strong><a href=\"https:\/\/ifeelonline.com\/fr\/culture-positive\/?partner=ifeel_internLinkPost\">culture positive du bien-\u00eatre mental<\/a><\/strong>. Une approche sur mesure et centr\u00e9e sur les personnes qui place la sant\u00e9 de vos collaborateurs au centre, en tant que pilier fondamental pour<strong><a href=\"https:\/\/ifeelonline.com\/fr\/guide-pour-renforcer-votre-strategie-en-matiere-de-talents\/?partner=ifeel_internLinkPost\">&nbsp;attirer et retenir les talents<\/a><\/strong>&nbsp;ainsi que pour renforcer leur sentiment d\u2019appartenance.<\/p>\n\n\n\n<p><strong>Une solution unique, compl\u00e8te et \u00e9volutive&nbsp;<\/strong>qui utilise la puissance des donn\u00e9es pour fournir une compr\u00e9hension holistique du&nbsp;<strong><a href=\"https:\/\/ifeelonline.com\/fr\/soutien-psychologique-en-entreprise-un-atout-pour-vos-colloborateurs\/\">bien-\u00eatre psychologique de vos employ\u00e9s<\/a><\/strong>, tout en garantissant la qualit\u00e9 du service et la confidentialit\u00e9 pour votre \u00e9quipe.<\/p>\n\n\n\n<p>Nous esp\u00e9rons que cet article sur\u00a0<strong>la r\u00e9silience des dirigeants\u00a0<\/strong>vous a int\u00e9ress\u00e9. Pour plus d\u2019informations sur ifeel en mati\u00e8re de bien-\u00eatre mental pour les entreprises,\u00a0<strong><a href=\"https:\/\/ifeelonline.com\/fr\/demander-une-demo\/?partner=ifeel_internLinkPost\">contactez-nous<\/a><\/strong>.<\/p>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Pourquoi les strat\u00e9gies de r\u00e9silience pour les dirigeants sont-elles n\u00e9cessaires, me direz-vous ? La v\u00e9rit\u00e9 est que lorsque nous pensons aux responsabilit\u00e9s des managers et des leaders, elles ne se limitent pas \u00e0 la poursuite d&rsquo;objectifs ambitieux, mais aussi \u00e0 \u00eatre ce guide capable de conduire leurs \u00e9quipes \u00e0 travers une mer d&rsquo;incertitudes et de [&hellip;]<\/p>\n","protected":false},"author":53,"featured_media":11419,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"categories":[27,38],"tags":[],"class_list":["post-11418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-etre-au-travail","category-leadership"],"_links":{"self":[{"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/posts\/11418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/comments?post=11418"}],"version-history":[{"count":0,"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/posts\/11418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/media\/11419"}],"wp:attachment":[{"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/media?parent=11418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/categories?post=11418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifeelonline.com\/fr\/wp-json\/wp\/v2\/tags?post=11418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}