{"id":4782,"date":"2020-09-09T12:50:29","date_gmt":"2020-09-09T11:50:29","guid":{"rendered":"https:\/\/ifeelonline.com\/?p=4782"},"modified":"2021-10-05T09:42:54","modified_gmt":"2021-10-05T08:42:54","slug":"horror-tengo-que-tomar-una-decision-y-no-me-atrevo","status":"publish","type":"post","link":"https:\/\/ifeelonline.com\/es\/terapias-ifeel\/desarrollo-personal\/horror-tengo-que-tomar-una-decision-y-no-me-atrevo\/","title":{"rendered":"\u00a1Horror! Tengo que tomar una decisi\u00f3n y no me atrevo"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_81 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #51607e;color:#51607e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #51607e;color:#51607e\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ifeelonline.com\/es\/terapias-ifeel\/desarrollo-personal\/horror-tengo-que-tomar-una-decision-y-no-me-atrevo\/#Por_que_tanto_miedo\" >Por qu\u00e9 tanto miedo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ifeelonline.com\/es\/terapias-ifeel\/desarrollo-personal\/horror-tengo-que-tomar-una-decision-y-no-me-atrevo\/#Todo_el_mundo_tiene_miedo\" >Todo el mundo tiene miedo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ifeelonline.com\/es\/terapias-ifeel\/desarrollo-personal\/horror-tengo-que-tomar-una-decision-y-no-me-atrevo\/#El_miedo_paraliza\" >El miedo paraliza<\/a><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">\u00bfTiene todo el mundo <strong>miedo a equivocarse<\/strong>? Con car\u00e1cter general, s\u00ed. A no ser que haya alguna circunstancia de salud mental (una patolog\u00eda, un d\u00e9ficit muy severo de inteligencia) <strong>todo el mundo experimenta miedo<\/strong>, que es una de las emociones b\u00e1sicas -de hecho, la compartimos con muchos animales. Por supuesto, esto incluye miedo a equivocarse, a <strong>tomar malas decisiones<\/strong>, a hacer da\u00f1o a alguien, etc. Sin ese miedo, igual que sin el resto de emociones, <strong>la vida en sociedad ser\u00eda ca\u00f3tica<\/strong> y acabar\u00eda volvi\u00e9ndose tremendamente agresiva y tambi\u00e9n temeraria.<\/p>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"Por_que_tanto_miedo\"><\/span>Por qu\u00e9 tanto miedo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En algunas personas <strong>el miedo a cometer errores<\/strong> puede llegar a ocupar un espacio desmesurado. Como siempre, esto se debe a una interacci\u00f3n de factores en la que a menudo es dif\u00edcil distinguir cu\u00e1les son causas y cu\u00e1les son efectos de los dem\u00e1s. No obstante, en esa din\u00e1mica podemos observar para empezar <strong>caracter\u00edsticas intraps\u00edquicas<\/strong>, es decir, relativas a la propia personalidad, el estilo de afrontamiento o el estilo cognitivo de los individuos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<span class=\"entresacado\">Todo el mundo tiene miedo a equivocarse, la cuesti\u00f3n es qu\u00e9 herramientas posee para regular ese miedo y que no deje de ser \u00fatil<\/span>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este grupo in incluir\u00edamos el ser m\u00e1s <strong>inseguros<\/strong>, incluso <strong>catastrofistas<\/strong> (personas que siempre juzgan como la m\u00e1s probable la peor consecuencia de entre todas las posibles), con <strong>menor confianza en sus capacidades<\/strong> y habilidades, retra\u00eddos, <strong>perfeccionistas<\/strong> o m\u00e1s lentos a la hora de tomar decisiones, ya sea por manejar de manera poco fluida demasiadas opciones a la vez o por procesar lentamente las opciones que manejan&#8230; o simplemente por <strong>un funcionamiento muy obsesivo<\/strong> (repasar una y otra vez todos los pros y todos los contras de las diferentes opciones) y, por tanto, poco fluido y espont\u00e1neo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"380\" src=\"https:\/\/ifeelonline.com\/wp-content\/uploads\/2020\/09\/kelly-sikkema-6mUIYJvS2_I-unsplash-1.jpg\" alt=\"\" class=\"wp-image-4784\" srcset=\"https:\/\/ifeelonline.com\/es\/wp-content\/uploads\/2020\/09\/kelly-sikkema-6mUIYJvS2_I-unsplash-1.jpg 708w, https:\/\/ifeelonline.com\/es\/wp-content\/uploads\/2020\/09\/kelly-sikkema-6mUIYJvS2_I-unsplash-1-300x161.jpg 300w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><\/figure>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de estos factores intraps\u00edquicos<strong> tambi\u00e9n influyen mucho las experiencias que hayamos tenido<\/strong> en la vida. Por ejemplo, si hemos cometido graves errores en el pasado es perfectamente normal (y \u00fatil) el tener mucho <strong>miedo a cometerlos de nuevo en el futuro<\/strong>. De hecho es un signo de inteligencia, ya que esa emoci\u00f3n nos va a predisponer para tomar medidas preventivas.<\/p>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"Todo_el_mundo_tiene_miedo\"><\/span>Todo el mundo tiene miedo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Todo el mundo, en seg\u00fan qu\u00e9 situaciones, debe tener miedo a equivocarse. Lo contrario ser\u00eda <strong>propio de personas narcisistas<\/strong>, desconectadas de sus verdaderas capacidades y carencias, lo cual les puede llevar a realizar conductas temerarias o da\u00f1inas para s\u00ed mismas u otras personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obviamente, ante <strong>tareas muy sencillas o que tenemos muy entrenadas <\/strong>ese miedo desciende a cero o bien a un nivel muy asumible. Por ejemplo, si nunca he hecho una tortilla de patata y me enfrento a mi primera vez, lo normal es que tenga una cierta inquietud por c\u00f3mo me va a quedar. Sin embargo, si he preparado ese plato cientos de veces me voy a <em>ocupar<\/em> de que me salga bien, m\u00e1s que preocuparme (<strong>la preocupaci\u00f3n es el correlato cognitivo de la emoci\u00f3n miedo<\/strong>). Es decir, deseo que la tortilla salga bien, pero conf\u00edo en que me va a quedar bien porque ya ha sucedido otras veces y eso va a hacer que incluso gran parte del proceso de preparar la tortilla suceda de manera bastante autom\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salvando las distancias, esto es aplicable a <strong>un cirujano principiante <\/strong>o a uno que ha hecho la misma operaci\u00f3n cientos de veces. O a un actor que sube al escenario: cu\u00e1ntas veces <strong>actores muy veteranos y reconocidos<\/strong> afirman que siguen sintiendo nervios al salir a escena. Claro: est\u00e1n vivos, se toman en serio su tarea, entienden cada funci\u00f3n como algo nuevo aunque se repita, pero evidentemente <strong>cuentan con el peso de la experiencia <\/strong>para regular adecuadamente esa inquietud, o miedo, de modo que no se convierta en algo paralizante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que tener en cuenta tambi\u00e9n que, en cierto sentido, el miedo es directamente proporcional a <strong>lo que consideramos que nos jugamos con cada conducta o decisi\u00f3n<\/strong>, pero que est\u00e1 acompa\u00f1ado de otros factores que pueden atenuarlo o dispararlo.<\/p>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"El_miedo_paraliza\"><\/span>El miedo paraliza<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Miedo e inseguridad son pr\u00e1cticamente sin\u00f3nimos. El miedo es la emoci\u00f3n relacionada con <strong>la percepci\u00f3n de una amenaza para nuestra integridad<\/strong> o bienestar, es decir, el miedo es lo que sentimos cuando no sentimos seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por supuesto existen personas m\u00e1s o menos seguras de s\u00ed mismas, <strong>con buena autoestima<\/strong>, flexibles, optimistas, de buen conformar, abiertas a la experiencia, indulgentes consigo mismas, etc. Estas caracter\u00edsticas las protegen de <strong>quedar paralizadas ante una decisi\u00f3n<\/strong>. Esto no quiere decir que no tengan miedo a equivocarse (la ausencia de este miedo no es una virtud, sino un problema), pero lo tienen en dosis manejables y saben trascenderlo, probablemente porque <strong>saben que, como son humanas, pueden equivocarse <\/strong>y que, si eso ocurre, sabr\u00e1n manejar bien esos errores sin culparse excesivamente por ellos.<\/p>\n\n\n\n<h3>El an\u00e1lisis que nos atrapa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En los \u00faltimos a\u00f1os se ha puesto muy de moda la expresi\u00f3n <strong>\u201cpar\u00e1lisis por an\u00e1lisis\u201d<\/strong>. Esta par\u00e1lisis es fruto de un desmesurado <strong>af\u00e1n de control<\/strong> sobre los diferentes factores que influyen en nuestra vida y de la fantas\u00eda de que, incluso en una decisi\u00f3n muy complicada, podemos -si lo repasamos todo una y otra vez- <strong>llegar a la decisi\u00f3n perfecta y as\u00e9ptica <\/strong>en la que el nivel de error ser\u00e1 nulo y el nivel de satisfacci\u00f3n ser\u00e1 \u00f3ptimo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"380\" src=\"https:\/\/ifeelonline.com\/wp-content\/uploads\/2020\/09\/neonbrand-Cmz06-0btw-unsplash-1.jpg\" alt=\"\" class=\"wp-image-4785\" srcset=\"https:\/\/ifeelonline.com\/es\/wp-content\/uploads\/2020\/09\/neonbrand-Cmz06-0btw-unsplash-1.jpg 708w, https:\/\/ifeelonline.com\/es\/wp-content\/uploads\/2020\/09\/neonbrand-Cmz06-0btw-unsplash-1-300x161.jpg 300w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos incurrir en este fen\u00f3meno <strong>cuando nos enfrentamos a decisiones muy trascendentales<\/strong> de la vida pero tambi\u00e9n en situaciones mucho m\u00e1s banales como a la hora de decidir si compramos o no una l\u00e1mpara, por ejemplo. Cuando la par\u00e1lisis se vuelve muy extrema<strong> genera mucha angustia<\/strong>, que no es sino una reacci\u00f3n de la familia del miedo. Esa angustia acompa\u00f1a a una tormenta de dudas que va soltando rayos y centellas en nuestra mente: <strong>\u00bfestar\u00e9 haciendo lo correcto, cu\u00e1l ser\u00e1 la consecuencia de mi decisi\u00f3n?<\/strong> Por otro lado, esa angustia puede diluirse una vez que se consigue desbloquear la situaci\u00f3n y se opta por alg\u00fan camino, lo cual <strong>permite ver los resultados positivos <\/strong>de haber tirado por ah\u00ed, pero hasta que se llega a ese punto el camino puede resultar realmente farragoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, est\u00e1 muy bien <strong>examinar todos los escenarios posibles<\/strong> a la hora de tomar una decisi\u00f3n y medir los <strong>diferentes grados y tipos de riesgo<\/strong> a los que nos exponemos en cada una de las alternativas posibles. Sin embargo, <strong>al final hay que decidir<\/strong>. Evidentemente, las decisiones f\u00e1ciles o perfectas existen pero se toman r\u00e1pidamente y no generan conflictos. De hecho muchas veces las tomamos de manera tan \u00e1gil que hasta parecen autom\u00e1ticas.<\/p>\n\n\n\n<span class=\"entresacado\">A veces la \u00fanica decisi\u00f3n posible es dejar de intentar decidir. Pero conscientemente<\/span>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cambio, <strong>si una decisi\u00f3n nos est\u00e1 costando<\/strong>, incluso si nos est\u00e1 costando mucho, eso quiere decir que <strong>ninguno de los escenarios es perfecto <em>a priori<\/em><\/strong> y que todos tienen sus pros y sus contras, pero que debemos optar por alguno de ellos <strong>si de verdad queremos avanzar<\/strong>. Cuando, por la raz\u00f3n que sea, llegamos a la conclusi\u00f3n de que nos resulta imposible elegir una opci\u00f3n, los expertos en la llamada<strong> \u201cpar\u00e1lisis por an\u00e1lisis\u201d <\/strong>recomiendan asumir conscientemente que no es el momento de tomar una decisi\u00f3n sobre este asunto y es eso precisamente lo que se convierte en la decisi\u00f3n. Es decir, si definitivamente no lo vemos claro, entonces <strong>es mejor dejar el tema reposar <\/strong>y salir durante un tiempo de ese laberinto improductivo para poder poner nuestras energ\u00edas en otros asuntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede que ahora mismo te hayas sumergido en <strong>un proceso de decisi\u00f3n importante del que no acabas de salir<\/strong>, o quiz\u00e1 ya sabes cu\u00e1l es la opci\u00f3n que -al menos en tu mente- m\u00e1s te conviene pero <strong>no te lanzas a dar el paso<\/strong> definitivo y sabes que eso solo est\u00e1 empeorando las cosas. Si es tu caso entonces es importante que te plantees recibir alg\u00fan tipo de ayuda o asesoramiento externo. Eso te permitir\u00e1 <strong>ver las cosas desde una perspectiva renovada y neutral<\/strong> y te puede ayudar a dar el \u00faltimo repaso a los pros y contras de las opciones que tienes entre manos. No le des m\u00e1s vueltas y <strong>ponte en manos de un buen psic\u00f3logo<\/strong>: estamos aqu\u00ed para ayudarte.<\/p>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>\u00bfTiene todo el mundo miedo a equivocarse? Con car\u00e1cter general, s\u00ed. A no ser que haya alguna circunstancia de salud mental (una patolog\u00eda, un d\u00e9ficit muy severo de inteligencia) todo el mundo experimenta miedo, que es una de las emociones b\u00e1sicas -de hecho, la compartimos con muchos animales. Por supuesto, esto incluye miedo a equivocarse, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":4783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"categories":[486],"tags":[],"class_list":["post-4782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-personal"],"_links":{"self":[{"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/posts\/4782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/comments?post=4782"}],"version-history":[{"count":0,"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/posts\/4782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/media\/4783"}],"wp:attachment":[{"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/media?parent=4782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/categories?post=4782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifeelonline.com\/es\/wp-json\/wp\/v2\/tags?post=4782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}